

{"id":5049,"date":"2021-01-19T16:48:00","date_gmt":"2021-01-19T15:48:00","guid":{"rendered":"https:\/\/www.camping-airial.com\/2021\/01\/19\/festival-toros-y-salsa-en-dax\/"},"modified":"2023-01-04T18:09:46","modified_gmt":"2023-01-04T17:09:46","slug":"festival-toros-y-salsa-en-dax","status":"publish","type":"post","link":"https:\/\/www.camping-airial.com\/es\/2021\/01\/19\/festival-toros-y-salsa-en-dax\/","title":{"rendered":"Festival Toros y Salsa en Dax"},"content":{"rendered":"\n\n[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb3px|auto||auto||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||1px|||\u00bb global_colors_info=\u00bb{}\u00bb]<p>Del 10 al 12 de septiembre de 2021 se celebrar\u00e1 un festival reconocido por los m\u00fasicos y el p\u00fablico amante de la salsa y el baile latino. Toros y salsa se ha convertido en EL lugar de encuentro de los salseros aficionados y profesionales.<\/p>\n<p>\u00danico festival de este tipo en Europa, ofrece seis grandes conciertos de renombre gratuitos y abiertos a todos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n","protected":false},"excerpt":{"rendered":"<p>Del 10 al 12 de septiembre de 2021 se celebrar\u00e1 un festival reconocido por los m\u00fasicos y el p\u00fablico amante de la salsa y el baile latino. Toros y salsa se ha convertido en EL lugar de encuentro de los salseros aficionados y profesionales. \u00danico festival de este tipo en Europa, ofrece seis grandes conciertos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[103],"tags":[],"class_list":["post-5049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"_links":{"self":[{"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/posts\/5049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/comments?post=5049"}],"version-history":[{"count":0,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/posts\/5049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/media\/3758"}],"wp:attachment":[{"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/media?parent=5049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/categories?post=5049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camping-airial.com\/es\/wp-json\/wp\/v2\/tags?post=5049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}